{"id":12462,"date":"2022-06-02T11:03:31","date_gmt":"2022-06-02T18:03:31","guid":{"rendered":"https:\/\/thereser.org\/event\/colores-de-debussy-y-crumb\/"},"modified":"2025-03-10T15:38:13","modified_gmt":"2025-03-10T22:38:13","slug":"colores-de-debussy-y-crumb","status":"publish","type":"tribe_events","link":"https:\/\/thereser.org\/es\/event\/colores-de-debussy-y-crumb\/","title":{"rendered":"Colores de Debussy y Crumb"},"content":{"rendered":"<p>Claude Debussy y el pionero estadounidense George Crumb son maestros en la creaci\u00f3n de vibrantes caleidoscopios sonoros. Debussy captura todo el color, la luz y la emoci\u00f3n de un cuadro impresionista. Con A Journey Beyond Time, Crumb combina la voz humana con un conjunto de m\u00e1s de 100 instrumentos para explorar el coraz\u00f3n y el alma de los espirituales negros americanos.<\/p>\n<p>DEBUSSY Cuarteto de cuerda en sol menor<br \/>\nDAVID LUDWIG &#8216;El canto del cisne&#8217; para viol\u00edn y piano (2013)<br \/>\nGEORGE CRUMB American Songbook II &#8211; &#8216;Un viaje m\u00e1s all\u00e1 del tiempo&#8217;<\/p>\n<p>M\u00fasicos: <em>Gloria Chien, Anna Lee, Ellen Hwangbo, Benjamin Beilman, Kenneth Overton, Sandbox Percussion<\/em><\/p>\n<p>Preludio para j\u00f3venes artistas a las 18.30 horas.<\/p>\n<p><strong>Procedimientos y precauciones de CMNW relacionados con COVID:<\/strong><\/p>\n<ul>\n<li>En la puerta se exigir\u00e1 a todos los asistentes un justificante de vacunaci\u00f3n y de vacunaci\u00f3n de refuerzo.<\/li>\n<li>Las mascarillas son obligatorias en interiores, independientemente del estado de vacunaci\u00f3n, en todo momento, excepto para tomar brevemente una bebida.<\/li>\n<\/ul>\n<p><em>Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/protect-us.mimecast.com\/s\/6RwiC73q6BSry4T8CMVv?domain=cmnw.org\" target=\"_blank\" rel=\"noopener\">cmnw.org<\/a> <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claude Debussy y el pionero estadounidense George Crumb son maestros en la creaci\u00f3n de vibrantes caleidoscopios sonoros. Debussy captura todo el color, la luz y la emoci\u00f3n de un cuadro&#8230;<\/p>\n","protected":false},"author":8,"featured_media":10913,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_wp_rev_ctl_limit":""},"tags":[],"tribe_events_cat":[],"class_list":["post-12462","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/12462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/12462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media\/10913"}],"wp:attachment":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media?parent=12462"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tags?post=12462"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=12462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}