{"id":17164,"date":"2025-01-14T13:46:25","date_gmt":"2025-01-14T21:46:25","guid":{"rendered":"https:\/\/thereser.org\/event\/clase-de-ukelele-para-todas-las-edades-2\/"},"modified":"2025-03-11T10:22:24","modified_gmt":"2025-03-11T17:22:24","slug":"clase-de-ukelele-para-todas-las-edades-2","status":"publish","type":"tribe_events","link":"https:\/\/thereser.org\/es\/event\/clase-de-ukelele-para-todas-las-edades-2\/","title":{"rendered":"\u00a1Clase de ukelele para todas las edades!"},"content":{"rendered":"<p>Descubre la alegr\u00eda del ukelele: \u00a1clase de principiantes para todas las edades!<\/p>\n<p>Aprende a tocar el ukelele con nuestra clase especialmente seleccionada para principiantes de todas las edades. Ya sea que sea un joven entusiasta o alguien que busca aprender un nuevo pasatiempo m\u00e1s adelante en la vida, esta clase est\u00e1 dise\u00f1ada para ser inclusiva y agradable para todos.<\/p>\n<p>Lo que aprender\u00e1s:<\/p>\n<p>Acordes b\u00e1sicos y rasgueo: Empezaremos desde el principio, aprendiendo a sujetar y afinar el ukelele, y avanzaremos hasta dominar los acordes fundamentales y los patrones de rasgueo.<\/p>\n<p>Canciones: Aprender\u00e1s a tocar canciones que inspiran y animan, haciendo que tus sesiones de pr\u00e1ctica sean divertidas y gratificantes.<\/p>\n<p>Ritmo y sincronizaci\u00f3n: Desarrollar un s\u00f3lido sentido del ritmo y la sincronizaci\u00f3n, esencial para tocar m\u00fasica con otros o simplemente disfrutar por su cuenta.<\/p>\n<p>T\u00e9cnica y postura: Aprenda las t\u00e9cnicas de juego y la postura adecuadas para garantizar la comodidad y la eficiencia mientras juega.<\/p>\n<p>Las clases tienen lugar los s\u00e1bados: 1 PM-2 PM<br \/>\n<a href=\"https:\/\/secure.thereser.org\/1285\/1287\">15 de marzo<\/a><br \/>\n<a href=\"https:\/\/secure.thereser.org\/1285\/1288\">22 de marzo<\/a><br \/>\n<a href=\"https:\/\/secure.thereser.org\/1285\/1289\">29 de marzo<\/a><\/p>\n<p>Las clases individuales cuestan $ 25 \/ $ 20 para personas mayores.<br \/>\nSi te inscribes en cuatro o m\u00e1s de nuestras clases de primavera en un solo pedido, recibir\u00e1s un 20% de descuento. (Se aplica autom\u00e1ticamente en su carrito). <\/p>\n<p>Se requiere una <a href=\"https:\/\/thereser.org\/wp-content\/uploads\/2023\/12\/PRCA-waiver-fillable-1.pdf\">renuncia<\/a> firmada para asistir a las clases. Todos los estudiantes deber\u00e1n traer su propio instrumento y un l\u00e1piz.<\/p>\n<p>Lugares para comprar y sugerencias&#8230;<\/p>\n<p>Portland Music Company \/ Beaverton Ubicaci\u00f3n<br \/>\n: 10075 SW Beaverton, Hillsdale Hwy, Beaverton, OR 97005<\/p>\n<p>Centro<br \/>\nde Guitarra 9575 SW Cascade Ave, Beaverton, OR 97008<\/p>\n<p>Si compras en l\u00ednea, te recomendamos estas marcas:<br \/>\nKala \/ Kona \/ Martin<\/p>\n<p>Evite las marcas baratas ($50 o menos) m\u00e1s parecidas a los juguetes y dif\u00edciles de mantener.<\/p>\n<p>Adulto mayor: $20 \/ 4+ descuento $16<\/p>\n<p>Clase: $25 \/ 4+ descuento $20<\/p>\n<p>La clase est\u00e1 limitada a 20 estudiantes<\/p>\n<p>Ubicaci\u00f3n: The LAB en The Reser<\/p>\n<p>Profesor: Francis Doo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre la alegr\u00eda del ukelele: \u00a1clase de principiantes para todas las edades! Aprende a tocar el ukelele con nuestra clase especialmente seleccionada para principiantes de todas las edades. Ya sea&#8230;<\/p>\n","protected":false},"author":8,"featured_media":17345,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_wp_rev_ctl_limit":""},"tags":[183],"tribe_events_cat":[181],"class_list":["post-17164","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-clase","tribe_events_cat-clases","cat_clases"],"acf":[],"_links":{"self":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/17164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/17164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media\/17345"}],"wp:attachment":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media?parent=17164"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tags?post=17164"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=17164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}