{"id":17221,"date":"2025-01-14T21:20:36","date_gmt":"2025-01-15T05:20:36","guid":{"rendered":"https:\/\/thereser.org\/event\/clase-de-armonica-para-principiantes-2\/"},"modified":"2025-03-16T11:58:19","modified_gmt":"2025-03-16T18:58:19","slug":"clase-de-armonica-para-principiantes-2","status":"publish","type":"tribe_events","link":"https:\/\/thereser.org\/es\/event\/clase-de-armonica-para-principiantes-2\/","title":{"rendered":"Clase de Arm\u00f3nica para principiantes"},"content":{"rendered":"<p>Exploraremos t\u00e9cnicas b\u00e1sicas, como c\u00f3mo tocar una sola nota y melod\u00edas simples, ejecuci\u00f3n r\u00edtmica, articulaci\u00f3n y temas m\u00e1s avanzados.<br \/>\n\u00a1Todos los niveles son bienvenidos!<\/p>\n<p>Las clases se llevan a cabo los domingos: 10 a.m.-11 a.m.<br \/>\n<a href=\"https:\/\/secure.thereser.org\/1296\/1299\">16 de marzo<\/a><br \/>\n<a href=\"https:\/\/secure.thereser.org\/1296\/1300\">23 de marzo<\/a><br \/>\n<a href=\"https:\/\/secure.thereser.org\/1296\/1301\">06 de abril<\/a><\/p>\n<p>NOTA IMPORTANTE: Por favor, traiga una llave de arm\u00f3nica diat\u00f3nica &#8220;C&#8221; de diez orificios (La Hohner special 20 es una gran opci\u00f3n)<\/p>\n<p>Las clases individuales cuestan $ 25 \/ $ 20 para personas mayores.<\/p>\n<p>Si te inscribes en cuatro o m\u00e1s de nuestras clases de primavera en un solo pedido, recibir\u00e1s un 20% de descuento. (El descuento se aplicar\u00e1 autom\u00e1ticamente en su carrito).<br \/>\nSe requiere una <a href=\"https:\/\/thereser.org\/wp-content\/uploads\/2023\/12\/PRCA-waiver-fillable-1.pdf\">renuncia<\/a> firmada para asistir a las clases. Trae tu propia arm\u00f3nica.<br \/>\nAdulto mayor: $20 \/ 4+ descuento $16<br \/>\nClase: $25 \/ 4+ descuento $20<br \/>\nLa clase est\u00e1 limitada a 20 estudiantes. Ubicaci\u00f3n: The LAB en The Reser.<br \/>\nProfesor: David Lipkind  <\/p>\n<p>David Lipkind ha estado ense\u00f1ando arm\u00f3nica y tocando m\u00fasica en Portland desde 1997. \u202fEnse\u00f1\u00f3 en el famoso centro de m\u00fasica folk Artichoke Music, en PCC, y contribuy\u00f3 con la arm\u00f3nica a innumerables \u00e1lbumes a lo largo de los a\u00f1os. \u202fHa tocado en vivo con muchos actos, y actualmente toca con Portland Country Underground, Woodbrain y Denver, entre otros.  <\/p>\n<p>La misi\u00f3n del Centro Patricia Reser para la Educaci\u00f3n Art\u00edstica y el Programa Comunitario es despertar la creatividad en todos nosotros proporcionando acceso a experiencias excepcionales de aprendizaje art\u00edstico a estudiantes, educadores y familias de nuestra comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exploraremos t\u00e9cnicas b\u00e1sicas, como c\u00f3mo tocar una sola nota y melod\u00edas simples, ejecuci\u00f3n r\u00edtmica, articulaci\u00f3n y temas m\u00e1s avanzados. \u00a1Todos los niveles son bienvenidos! Las clases se llevan a cabo&#8230;<\/p>\n","protected":false},"author":8,"featured_media":17362,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_wp_rev_ctl_limit":""},"tags":[183],"tribe_events_cat":[181],"class_list":["post-17221","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-clase","tribe_events_cat-clases","cat_clases"],"acf":[],"_links":{"self":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/17221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events\/17221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media\/17362"}],"wp:attachment":[{"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/media?parent=17221"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tags?post=17221"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thereser.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=17221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}